{"id":189,"date":"2018-11-23T14:59:23","date_gmt":"2018-11-23T12:59:23","guid":{"rendered":"https:\/\/www.utopiaengineering.com\/?page_id=189"},"modified":"2018-11-23T14:59:23","modified_gmt":"2018-11-23T12:59:23","slug":"invoices","status":"publish","type":"page","link":"https:\/\/www.utopiaengineering.com\/en\/software\/invoices\/","title":{"rendered":"INVOICES"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":183,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>INVOICES | Utopia Engineering<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.utopiaengineering.com\/en\/software\/invoices\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INVOICES | Utopia Engineering\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.utopiaengineering.com\/en\/software\/invoices\/\" \/>\n<meta property=\"og:site_name\" content=\"Utopia Engineering\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"admin\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.utopiaengineering.com\/#organization\",\"name\":\"KLK Utopia Engineering\",\"url\":\"https:\/\/www.utopiaengineering.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.utopiaengineering.com\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.utopiaengineering.com\/wp-content\/uploads\/2018\/11\/utopia_logo_200.png\",\"width\":200,\"height\":58,\"caption\":\"KLK Utopia Engineering\"},\"image\":{\"@id\":\"https:\/\/www.utopiaengineering.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.utopiaengineering.com\/#website\",\"url\":\"https:\/\/www.utopiaengineering.com\/\",\"name\":\"Utopia Engineering\",\"description\":\"Impossible IS Nothing\",\"publisher\":{\"@id\":\"https:\/\/www.utopiaengineering.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.utopiaengineering.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.utopiaengineering.com\/en\/software\/invoices\/#webpage\",\"url\":\"https:\/\/www.utopiaengineering.com\/en\/software\/invoices\/\",\"name\":\"INVOICES | Utopia Engineering\",\"isPartOf\":{\"@id\":\"https:\/\/www.utopiaengineering.com\/#website\"},\"datePublished\":\"2018-11-23T12:59:23+00:00\",\"dateModified\":\"2018-11-23T12:59:23+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.utopiaengineering.com\/en\/software\/invoices\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.utopiaengineering.com\/en\/wp-json\/wp\/v2\/pages\/189"}],"collection":[{"href":"https:\/\/www.utopiaengineering.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.utopiaengineering.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.utopiaengineering.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.utopiaengineering.com\/en\/wp-json\/wp\/v2\/comments?post=189"}],"version-history":[{"count":1,"href":"https:\/\/www.utopiaengineering.com\/en\/wp-json\/wp\/v2\/pages\/189\/revisions"}],"predecessor-version":[{"id":190,"href":"https:\/\/www.utopiaengineering.com\/en\/wp-json\/wp\/v2\/pages\/189\/revisions\/190"}],"up":[{"embeddable":true,"href":"https:\/\/www.utopiaengineering.com\/en\/wp-json\/wp\/v2\/pages\/183"}],"wp:attachment":[{"href":"https:\/\/www.utopiaengineering.com\/en\/wp-json\/wp\/v2\/media?parent=189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}